{"id":1,"count":44,"description":"","link":"https:\/\/salud.utp.edu.co\/especializacion-psiquiatria\/category\/sin-categoria\/","name":"Sin categor\u00eda","slug":"sin-categoria","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/salud.utp.edu.co\/especializacion-psiquiatria\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salud.utp.edu.co\/especializacion-psiquiatria\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/salud.utp.edu.co\/especializacion-psiquiatria\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/salud.utp.edu.co\/especializacion-psiquiatria\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}