{"id":9,"date":"2018-04-23T15:59:26","date_gmt":"2018-04-23T20:59:26","guid":{"rendered":"https:\/\/salud.utp.edu.co\/gerencia-en-sistemas-de-salud\/sin-categoria\/vision\/"},"modified":"2022-09-28T11:19:27","modified_gmt":"2022-09-28T16:19:27","slug":"vision","status":"publish","type":"post","link":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/sin-categoria\/vision\/","title":{"rendered":"Visi\u00f3n"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/media2.utp.edu.co\/programas\/7\/vision.png\" alt=\"vision\" width=\"300\"\/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\"><strong>Visi\u00f3n<\/strong><\/h3>\n\n\n\n<p><span class=\"post-content__span\"> Para el 2025, la Especializaci\u00f3n de Gerencia en Sistemas de Salud ser\u00e1 un posgrado con excelente reconocimiento social nacional e internacional primero porque forma talento humano con solvencia suficiente para responder a las necesidades de funcionamiento del Sistema de Salud vigente y segundo porque es un eslab\u00f3n s\u00f3lido para que los egresados puedan desarrollar estudios posteriores a nivel de maestr\u00eda conducentes a la investigaci\u00f3n y la innovaci\u00f3n con generaci\u00f3n de conocimiento cr\u00edtico que permita adaptar los sistemas de salud a las expectativas de la sociedad y sus contextos socio culturales, contribuyendo as\u00ed a mejorar sus condiciones de vida y por ende sus niveles de bienestar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visi\u00f3n Para el 2025, la Especializaci\u00f3n de Gerencia en Sistemas de Salud ser\u00e1 un posgrado con excelente reconocimiento social nacional [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/posts\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":2,"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/posts\/9\/revisions"}],"predecessor-version":[{"id":10187,"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/posts\/9\/revisions\/10187"}],"wp:attachment":[{"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/media?parent=9"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/categories?post=9"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/tags?post=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}