{"id":10115,"date":"2022-08-17T08:44:51","date_gmt":"2022-08-17T13:44:51","guid":{"rendered":"https:\/\/salud.utp.edu.co\/gerencia-en-sistemas-de-salud\/?p=10115"},"modified":"2025-11-24T15:23:59","modified_gmt":"2025-11-24T20:23:59","slug":"descripcion","status":"publish","type":"post","link":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/sin-categoria\/descripcion\/","title":{"rendered":"Descripci\u00f3n"},"content":{"rendered":"\n<p><span class=\"post-content__span\"> El programa forma especialistas con conocimientos y habilidades en el \u00e1rea de la gerencia y administraci\u00f3n, aprovechando los recursos f\u00edsicos, t\u00e9cnicos y humanos. Adicionalmente, brinda competencias para responder a las necesidades del medio laboral en gerencia de instituciones de salud y de salud p\u00fablica.<\/p>\n\n\n\n<p><span class=\"post-content__span\"> <strong>Contacto: <a href=\"mailto:posgradossalud@utp.edu.co\"><strong><a>gerenciasistemasalud@utp.edu.co<\/a><\/strong><\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El programa forma especialistas con conocimientos y habilidades en el \u00e1rea de la gerencia y administraci\u00f3n, aprovechando los recursos f\u00edsicos, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7],"class_list":["post-10115","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-descripcion"],"_links":{"self":[{"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/posts\/10115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/comments?post=10115"}],"version-history":[{"count":2,"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/posts\/10115\/revisions"}],"predecessor-version":[{"id":10313,"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/posts\/10115\/revisions\/10313"}],"wp:attachment":[{"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/media?parent=10115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/categories?post=10115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salud.utp.edu.co\/especializacion-gerencia-en-sistemas-de-salud\/wp-json\/wp\/v2\/tags?post=10115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}